{"id":6064,"date":"2018-03-18T11:40:52","date_gmt":"2018-03-18T10:40:52","guid":{"rendered":"http:\/\/urbinavolant.com\/scripta\/?p=6064"},"modified":"2018-03-18T11:40:52","modified_gmt":"2018-03-18T10:40:52","slug":"no-tienes-que-verlo-para-saber-que-tienes-que-verlo-el-museo-del-louvre","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/scripta\/no-tienes-que-verlo-para-saber-que-tienes-que-verlo-el-museo-del-louvre\/","title":{"rendered":"No tienes que verlo para saber que tienes que verlo &#8211; El museo del Louvre"},"content":{"rendered":"<p><a href=\"https:\/\/urbinavolant.com\/scripta\/no-tienes-que-verlo-para-saber-que-tienes-que-verlo-el-museo-del-louvre\/louvre_monalisa-2\/\" rel=\"attachment wp-att-6079\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6079\" src=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_monalisa-1.png?resize=625%2C889&#038;ssl=1\" alt=\"\" width=\"625\" height=\"889\" srcset=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_monalisa-1.png?resize=720%2C1024&amp;ssl=1 720w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_monalisa-1.png?resize=211%2C300&amp;ssl=1 211w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_monalisa-1.png?resize=768%2C1092&amp;ssl=1 768w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_monalisa-1.png?w=867&amp;ssl=1 867w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La publicidad es un tipo de discurso persuasivo en el que es muy frecuente que se omitan elementos. No es necesario que haya una argumentaci\u00f3n completa para que esta llegue al receptor de manera exitosa y eficaz. Esto, que ocurre de modo general en toda la comunicaci\u00f3n publicitaria, se consigue plasmar de manera muy inteligente en la campa\u00f1a realizada por Miami Ad School, una agencia alemana, para el Museo del Louvre.<\/p>\n<p style=\"text-align: justify;\">El lema de la campa\u00f1a es <em>You don\u2019t have to see it, to know you have to see it<\/em>\u00a0(No tienes que verlo para saber que tienes que verlo. Se trata de una bonita paradoja que evidencia que las obras que pueden apreciarse en el Louvre son sobradamente conocidas por el p\u00fablico, por lo que no necesitan ser mostradas m\u00e1s que de forma pixelada en las im\u00e1genes de la campa\u00f1a. Por lo tanto, la campa\u00f1a se basa en lo que no muestra y todos comprenden: No tienes que verlo [<strong>aqu\u00ed<\/strong>] para verlo [<strong>en el Louvre<\/strong>]. Desde el punto de vista cognitivo, entendemos lo que no est\u00e1 por lo que est\u00e1. O, lo que es lo mismo, es mucho mejor ver la aut\u00e9ntica realidad de lo que ya conocemos que ver una imagen. Ser\u00eda la elevaci\u00f3n por sublimaci\u00f3n del <em>Ceci n&#8217;est pas un pipe<\/em> de Magritte (o, visto de una manera m\u00e1s cr\u00edtica, su reducci\u00f3n al absurdo).<\/p>\n<p style=\"text-align: justify;\">Para juzgar si este reconocimiento es completo por parte de todos los receptores, dejo, adem\u00e1s de la <em>Mona Lisa <\/em>que\u00a0encabeza la entrada, las im\u00e1genes del <em>Juramento de los Horacios, \u00a0La Libertad guiando al pueblo <\/em>y<em> La balsa de la Medusa<\/em>. Basta con que pinch\u00e9is sobre cada imagen.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-6064 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/urbinavolant.com\/scripta\/louvre_juramentohoracios\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_juramentohoracios.png?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_juramentohoracios.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_juramentohoracios.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_juramentohoracios.png?resize=266%2C266&amp;ssl=1 266w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_juramentohoracios.png?resize=184%2C184&amp;ssl=1 184w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_juramentohoracios.png?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/urbinavolant.com\/scripta\/louvre_libertad\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_libertad.png?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_libertad.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_libertad.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_libertad.png?resize=266%2C266&amp;ssl=1 266w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_libertad.png?resize=184%2C184&amp;ssl=1 184w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_libertad.png?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/urbinavolant.com\/scripta\/louvre_balsamedusa\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_balsamedusa.png?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_balsamedusa.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_balsamedusa.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_balsamedusa.png?resize=266%2C266&amp;ssl=1 266w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_balsamedusa.png?resize=184%2C184&amp;ssl=1 184w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2018\/03\/louvre_balsamedusa.png?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>La informaci\u00f3n sobre esta campa\u00f1a me lleg\u00f3 a trav\u00e9s de la web <a href=\"http:\/\/www.adsoftheworld.com\">Ads of the World<\/a>.<\/p>\n<p>Esta entrada, publicada primero en <em>ScriptaManent<\/em>, aparecer\u00e1 tambi\u00e9n en mi blog personal, <a href=\"http:\/\/urbinavolant.com\/verbavolant\/\"><em>VerbaVolant<\/em><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La publicidad es un tipo de discurso persuasivo en el que es muy frecuente que se omitan elementos. No es necesario que haya una argumentaci\u00f3n completa para que esta llegue al receptor de manera exitosa y eficaz. Esto, que ocurre de modo general en toda la comunicaci\u00f3n publicitaria, se consigue plasmar de manera muy inteligente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,9,12],"tags":[],"class_list":["post-6064","post","type-post","status-publish","format-standard","hentry","category-lengua","category-publicidad","category-retorica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3zkbD-1zO","_links":{"self":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts\/6064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/comments?post=6064"}],"version-history":[{"count":7,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts\/6064\/revisions"}],"predecessor-version":[{"id":6081,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts\/6064\/revisions\/6081"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/media?parent=6064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/categories?post=6064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/tags?post=6064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}