{"id":5952,"date":"2016-11-30T13:47:45","date_gmt":"2016-11-30T12:47:45","guid":{"rendered":"http:\/\/urbinavolant.com\/scripta\/?p=5952"},"modified":"2016-11-30T13:51:12","modified_gmt":"2016-11-30T12:51:12","slug":"argumentacion-di-lo-contrario-diciendo-lo-mismo-o-viceversa-y-sal-siempre-ganado","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/scripta\/argumentacion-di-lo-contrario-diciendo-lo-mismo-o-viceversa-y-sal-siempre-ganado\/","title":{"rendered":"Argumentaci\u00f3n: di lo contrario diciendo lo mismo o viceversa&#8230; y sal siempre ganado"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/flic.kr\/p\/nuDT75\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5963\" src=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2016\/11\/14107745076_8b99eb52fd_z.jpg?resize=625%2C415&#038;ssl=1\" alt=\"Hacienda-la-Colora\" width=\"625\" height=\"415\" srcset=\"https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2016\/11\/14107745076_8b99eb52fd_z.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2016\/11\/14107745076_8b99eb52fd_z.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2016\/11\/14107745076_8b99eb52fd_z.jpg?resize=207%2C136&amp;ssl=1 207w, https:\/\/i0.wp.com\/urbinavolant.com\/scripta\/wp-content\/uploads\/2016\/11\/14107745076_8b99eb52fd_z.jpg?resize=140%2C94&amp;ssl=1 140w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En <a href=\"http:\/\/Imagen de Eric Langley. A diferencia de la mayor parte de las entradas de este blog, las entradas sobre argumentaci\u00f3n, como todas las de este sitio web, est\u00e1n protegidas por derechos de autor. Si quieres utilizarlas, lo mejor es que te pongas en contacto con el autor en el formulario de contacto de la web.\">nuestra anterior entrada<\/a>, ense\u00f1\u00e1bamos que un recurso muy \u00fatil en las discusiones es dar la raz\u00f3n a tu adversario. Hoy vamos a seguir con una serie de recursos argumentativos \u00fatiles en los intercambios verbales hablando de la <em><strong>syncrisis<\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">La syncrisis es un <strong>recurso argumentativo m\u00e1gico<\/strong> porque <strong>tiene un poco de met\u00e1fora (o de s\u00edmil) y un poco de ant\u00edtesis<\/strong> o, como reza en el t\u00edtulo de esta entrada, es un recurso que nos sirve para decir lo contrario diciendo lo mismo o para decir lo mismo diciendo lo contrario. De este modo, con este recurso podemos comparar cosas opuestas o establecer distancias con cosas muy similares.<\/p>\n<p style=\"text-align: justify;\">Vamos a explicarnos:<\/p>\n<p style=\"text-align: justify;\">La <em>syncrisis<\/em>\u00a0sirve para <strong>comparar conceptos (o personas) opuestos para evaluar su valor relativo<\/strong>. Se establece una comparaci\u00f3n o equivalencia aparente entre dos elementos para <strong>hacer que uno prevalezca sobre otro<\/strong>. Imaginemos conversaciones como estas:<\/p>\n<ol style=\"list-style-type: upper-alpha;\">\n<li style=\"text-align: justify;\">Mira que eres cabezota.<\/li>\n<li>No, no de cabezota nada. Lo que soy es constante.<\/li>\n<\/ol>\n<ol style=\"list-style-type: upper-alpha;\">\n<li style=\"text-align: justify;\">Luis es una persona muy constante.<\/li>\n<li style=\"text-align: justify;\">\u00bfMuy constante? Lo que pasa es que es un cabezota.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">El primer caso, va a favor del segundo interlocutor. Desde luego, ser constante no es ni siquiera parecido a ser cabezota, pero B ha logrado establecer una equivalencia a su favor entre cosas opuestas. En el segundo caso, ocurre exactamente lo mismo, pero lo contrario (\u00bfveis, ya hemos hecho otra <em>syncrisis<\/em>): A alaba a Luis por su constancia, pero B. diferencia, comparando, la presunta constancia de Luis con su cabezoner\u00eda.<\/p>\n<p style=\"text-align: justify;\">Pongamos m\u00e1s ejemplos:<\/p>\n<ol style=\"list-style-type: upper-alpha;\">\n<li style=\"text-align: justify;\">Mar\u00eda tiene una capacidad tremenda para conocer y aprovechar las terapias alternativas.<\/li>\n<li style=\"text-align: justify;\">Con este \u00abdominio\u00bb de las terapias alternativas, lo que se demuestra es que Mar\u00eda es una iluminada.<\/li>\n<\/ol>\n<ol style=\"list-style-type: upper-alpha;\">\n<li style=\"text-align: justify;\">Lucas es un zote como la copa de un pino. No pilla ni una indirecta.<\/li>\n<li style=\"text-align: justify;\">Hija, no seas bruta. Digamos que es&#8230; limitado.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">En el primer ejemplo\u00a0se juega con conceptos referentes al conocimiento: A piensa que Mar\u00eda es una persona con gran capacidad, lo que presupone que es una persona inteligente. Sin embargo, B consigue descalificar las terapias alternativas: esa capacidad, de ser un elemento positivo, se convierte en un elemento negativo que no deja a Mar\u00eda en muy buen lugar. En el segundo, se matiza un t\u00e9rmino demasiado violento y despectivo (<em>zote<\/em>) sustituy\u00e9ndolo por un t\u00e9rmino m\u00e1s comprensivo. Hemos de notar que, en este \u00faltimo caso, dependiendo de la pronunciaci\u00f3n, tambi\u00e9n podemos introducir un tercer elemento: la iron\u00eda.<\/p>\n<p style=\"text-align: justify;\">En el cuarto cap\u00edtulo de la tercera temporada de la serie <em><a href=\"http:\/\/www.imdb.com\/title\/tt2543312\/\">Halt and Cath Fire<\/a>\u00a0<\/em>se utiliza en un di\u00e1logo una <em>syncrisis<\/em>\u00a0hablando, precisamente, de otros recursos expresivos:<\/p>\n<ol style=\"list-style-type: upper-alpha;\">\n<li style=\"text-align: justify;\">Es una met\u00e1fora.<\/li>\n<li style=\"text-align: justify;\">De hecho, es m\u00e1s una alegor\u00eda.<\/li>\n<\/ol>\n<ol style=\"list-style-type: upper-alpha;\">\n<li>Una alegor\u00eda es una met\u00e1fora.<\/li>\n<li>J\u00f3dete.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Entre A y B, se produce una discusi\u00f3n t\u00e9cnica (aunque, de hecho, dentro del di\u00e1logo es solo una peque\u00f1a an\u00e9cdota de corte dial\u00e9ctico). La posici\u00f3n de dominio argumentativo es para A, pese a la interpelaci\u00f3n de B. Tenemos, por lo tanto, dos <em>syncrisis<\/em>: en la primera, B hace notar la diferencia entre met\u00e1fora y alegor\u00eda (oposici\u00f3n de sin\u00f3nimos); en la segunda, A deja claro que, pese a ser dos cosas diferentes, una (la alegor\u00eda) se engloba dentro de otra (la met\u00e1fora). \u00bfQui\u00e9n gana? B, A, sin lugar a dudas.<\/p>\n<p style=\"text-align: justify;\">\u00bfQue un pol\u00edtico quiere defender un ataque de su ej\u00e9rcito? Pues a la interpelaci\u00f3n de \u00abEstamos en una guerra\u00bb nos dir\u00e1 \u00abNo es una guerra, es una manera de protegernos contra X\u00bb y se quedar\u00e1 tan fresco. \u00bfQue un terrorista\u00a0quiere justificar sus acciones? Pues le dir\u00e1 a un periodista que no hablemos de \u00abacci\u00f3n terrorista\u00bb, sino de \u00abconflicto armado\u00bb. Por supuesto, se preocupar\u00e1 tambi\u00e9n de denominar \u00abtregua\u00bb al cese de sus acciones. As\u00ed utilizar\u00e1 la <em>syncrisis<\/em>\u00a0para que todos pensemos que esos t\u00e9rminos son sin\u00f3nimos y que estamos hablando de bandos de un ej\u00e9rcito.<\/p>\n<p style=\"text-align: justify;\">En espa\u00f1ol, tenemos la palabra <em>sincretismo<\/em>, que tiene el mismo origen. En el <em>DLE<\/em> ya <a href=\"http:\/\/dle.rae.es\/?id=Xx6Aiyr\">nos dice<\/a> que, etimol\u00f3gicamente, significa &#8216;coalici\u00f3n de dos adversarios contra un tercero&#8217;. Los t\u00e9rminos, descompuestos, son\u00a0\u03c3\u03cd\u03bd (&#8216;juntos&#8217;, &#8216;con&#8217;) y\u00a0\u03ba\u03c1\u03af\u03c3\u03b9\u03c2 (&#8216;juicio&#8217;, &#8216;cr\u00edtica&#8217;). Por lo tanto, dos cosas que, unidas, sirven para criticar o poner en tela de juicio<\/p>\n<p style=\"text-align: justify;\">Estas entradas tienen un objetivo muy pr\u00e1ctico, as\u00ed que no descenderemos a detalles muy t\u00e9cnicos. Solo comentaremos que, curiosamente, no ha sido muy tratada en el \u00e1mbito hisp\u00e1nico, sino que se ha teorizado sobre ella b\u00e1sicamente en el anglosaj\u00f3n. Lo que no deja de ser interesante es c\u00f3mo, desde un punto de vista sem\u00e1ntico, el concepto de sinonimia y de antonimia a veces, aunque parezca una paradoja, est\u00e1n m\u00e1s pr\u00f3ximos de lo que parece. O no lo llamemos paradoja; llam\u00e9moslo, simplemente, algo\u00a0que se rige por una l\u00f3gica&#8230; diferente. Y vaya, ya hemos vuelto a la <em>syncrisis<\/em>&#8230;<\/p>\n<p style=\"text-align: justify;\">Imagen de <a href=\"https:\/\/flic.kr\/p\/nuDT75\">Hacienda-la-Colora<\/a>.<\/p>\n<p style=\"text-align: justify;\">\u00a9 A diferencia de la mayor parte de las entradas de este blog, las entradas sobre argumentaci\u00f3n \u00a0est\u00e1n protegidas por derechos de autor.\u00a0Si quieres utilizarlas, lo mejor es que te pongas\u00a0en contacto conmigo en el <a href=\"https:\/\/urbinavolant.com\/scripta\/contacto\/\">formulario de contacto de la web<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En nuestra anterior entrada, ense\u00f1\u00e1bamos que un recurso muy \u00fatil en las discusiones es dar la raz\u00f3n a tu adversario. Hoy vamos a seguir con una serie de recursos argumentativos \u00fatiles en los intercambios verbales hablando de la syncrisis. La syncrisis es un recurso argumentativo m\u00e1gico porque tiene un poco de met\u00e1fora (o de s\u00edmil) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,3,12],"tags":[],"class_list":["post-5952","post","type-post","status-publish","format-standard","hentry","category-linguistica","category-pragmatica","category-retorica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3zkbD-1y0","_links":{"self":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts\/5952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/comments?post=5952"}],"version-history":[{"count":8,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts\/5952\/revisions"}],"predecessor-version":[{"id":5965,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/posts\/5952\/revisions\/5965"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/media?parent=5952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/categories?post=5952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/scripta\/wp-json\/wp\/v2\/tags?post=5952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}