{"id":5393,"date":"2024-03-28T12:09:28","date_gmt":"2024-03-28T11:09:28","guid":{"rendered":"https:\/\/urbinavolant.com\/pragmaubu\/?p=5393"},"modified":"2024-04-18T18:53:43","modified_gmt":"2024-04-18T17:53:43","slug":"compendio-para-explicar-las-presuposiciones-y-las-implicaturas","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/pragmaubu\/2024\/03\/28\/compendio-para-explicar-las-presuposiciones-y-las-implicaturas\/","title":{"rendered":"Compendio para explicar las presuposiciones y las implicaturas"},"content":{"rendered":"\n<p>Las reflexiones de Grice sobre las presuposiciones los distintos tipos de implicaturas pueden resultar complicados y han dado lugar a detalladas explicaciones por parte de los investigadores en Pragm\u00e1tica. <\/p>\n\n\n\n<p>Vamos a intentar dejar aqu\u00ed una breve s\u00edntesis para aclarar conceptos:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">PRESUPOSICIONES<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En la presuposici\u00f3n, la informaci\u00f3n contenida se deduce por completo del contenido del enunciado.<\/li>\n\n\n\n<li>Aporta una informaci\u00f3n que se considera conocida por los participantes de la actividad cuando se profese un enunciado.<\/li>\n\n\n\n<li>Las presuposiciones tienen un componente pragm\u00e1tico en la que medida en la que el hablante da por supuesto que hay una informaci\u00f3n que se da por conocida en el enunciado.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-dark-red-color\">(1) Lorca muri\u00f3 en 1936 en los inicios de la Guerra Civil.<br>(2) Lorca fue asesinado en 1936, en los inicios de la Guerra Civil.<\/mark><br><\/em>Del enunciado (1) se deduce que Lorca est\u00e1 muerto, adem\u00e1s de otros elementos, como que Federico Garc\u00eda Lorca existi\u00f3 y que en 1936 la Guerra Civil estaba en sus comienzos.  <br>Del enunciado (2) se deduce, adem\u00e1s, que Lorca no muri\u00f3 de manera accidental o natural.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">IMPLICATURAS CONVENCIONALES<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La implicatura convencional surge autom\u00e1ticamente del significado de un elemento ling\u00fc\u00edstico presente en el enunciado.<\/li>\n\n\n\n<li>Estas implicaturas se generan porque hay un significado convencional en determinadas part\u00edculas que se emplean en el enunciado.<\/li>\n\n\n\n<li>El valor de verdad de la implicatura convencional  no radica indispensablemente en lo que se dice: se parte de lo dicho mediante un enunciado y hay una informaci\u00f3n que se transmite como nueva.<\/li>\n\n\n\n<li>El elemento convencional afecta al significado para modularlo o especificarlo.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-dark-red-color has-text-color has-link-color wp-elements-f4c37fc5ce111046276f1ffb23541076\"><em>(3) Est\u00e1 sonando otra vez el maldito m\u00f3vil [ejemplo de Garc\u00eda Muga].<\/em><br>Lo dicho: est\u00e1 sonando otra vez el m\u00f3vil.<br>Lo implicado de manera convencional: el hablante tiene una actitud negativa hacia el m\u00f3vil.<br>[Por supuesto, hay tambi\u00e9n una presuposici\u00f3n: el m\u00f3vil ya hab\u00eda sonado antes.<\/p>\n\n\n\n<p class=\"has-dark-red-color has-text-color has-link-color wp-elements-335a9ef8614276e00c3f57f8ed9d4a77\"><em>(4) Ana es valenciana, pero no le gusta la paella.<br><\/em>Lo dicho: Anta es valenciana y no le gusta la paella.<br>Lo implicado de manera convencional: ser valenciana contrasta con que no le guste la paella.<\/p>\n\n\n\n<p><em>(5) Es espa\u00f1ol, pero no se echa la siesta.<br><\/em>Lo dicho: Es espa\u00f1ol y, por lo tanto, se echa la siesta.<br>Lo implicado de manera convencional: ser espa\u00f1ol conlleva el echarse la siesta.<\/p>\n\n\n\n<p>En los ejemplos se\u00f1alados, hay un elemento ling\u00fc\u00edstico (<em>maldito, pero, por lo tanto<\/em>) del que se extrae la informaci\u00f3n generalizada. En algunos casos, como el de los conectores, se genera una relaci\u00f3n causa-efecto.<\/p>\n\n\n\n<p>Las implicaturas convencionales han dado bastantes quebraderos de cabeza a los estudiosos y, de hecho, el mero concepto de implicatura convencional no deja de ser controvertido (Korta, 2020:17):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Parece que no se sugiere, sino que, directamente, se dice.<\/li>\n\n\n\n<li>Se asume que el significado convencional del enunciado es parte esencial de lo dicho, pero&nbsp; lo dicho es diferente de las implicaturas. Esta divisi\u00f3n no deja de ser contradictoria.<\/li>\n\n\n\n<li>El significado convencional de los enunciados se asigna a la Pragm\u00e1tica y no a la Sem\u00e1ntica.<\/li>\n<\/ul>\n\n\n\n<p>Por eso, m\u00e1s all\u00e1 de Grice, en Pragm\u00e1tica es habitual que, cuando nos referimos a las implicaturas, nos refiramos las implicaturas conversacionales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">IMPLICATURAS CONVERSACIONALES<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para que los intercambios comunicativos sean exitosos, la informaci\u00f3n aportada tiene que ser accesible para el receptor en el momento de la enunciaci\u00f3n, dado que existe una informaci\u00f3n que es necesaria para entender lo que el emisor ha querido decir.<\/li>\n\n\n\n<li>Adem\u00e1s, el receptor debe inferir la carga impl\u00edcita del enunciado gracias a que el receptor supone que existe una intenci\u00f3n comunicativa determinada por parte del emisor.<\/li>\n\n\n\n<li>No decir de manera expl\u00edcita todo lo que se quiere comunicar supone una evidente econom\u00eda ling\u00fc\u00edstica y el conocimiento del acto comunicativo hace que las posibilidades de interpretar de manera err\u00f3nea el enunciado sean relativamente peque\u00f1as.<\/li>\n\n\n\n<li>Es muy interesante observar que, en muchas ocasiones, el contenido esencial de la comunicaci\u00f3n es ese elemento impl\u00edcito.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Implicaturas conversacionales generalizadas<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El uso de determinados elementos ling\u00fc\u00edsticos <em>empuja<\/em> a interpretar los enunciados de una manera determinada. <\/li>\n\n\n\n<li>A diferencia de lo que ocurre en las implicaturas convencionales, esta interpretaci\u00f3n no forma parte de lo dicho, sino de la interpretaci\u00f3n de lo dicho.<\/li>\n\n\n\n<li>El sentido del enunciado se genera partiendo de ese elemento ling\u00fc\u00edstico, pero gracias al contexto.<\/li>\n\n\n\n<li>Es importante advertir (y eso las diferencia de las implicaturas particularizadas) que no dependen exclusivamente del contexto.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-dark-red-color has-text-color has-link-color wp-elements-05f1d5f65ad347e7e8e2ce7f137a9352\"><em>(6) Me puse los zapatos y sal\u00ed a la calle<br><\/em>Implicamos, de manera generalizada, que [primero] me puse los zapatos y [despu\u00e9s] sal\u00ed a la calle.<\/p>\n\n\n\n<p class=\"has-dark-red-color has-text-color has-link-color wp-elements-af76cd2954c503b1bddd355185511455\"><em>(7) Es muy inteligente y habla ruso<br><\/em>Implicamos, de manera generalizada, que el hecho de ser inteligente le hace saber idiomas que no todo el mundo conoce.<\/p>\n\n\n\n<p><em>(8) Mar\u00eda y Juan fueron al cine.<br><\/em>Implicamos, de manera generalizada, que tanto Mar\u00eda como Juan fueron al cine.<\/p>\n\n\n\n<p><em>(8) Estudi\u00e9 mucho y aprob\u00e9 el examen<br><\/em>Implicamos, de manera generalizada, que el hecho de estudiar mucho es la causa de aprobar el examen.<\/p>\n\n\n\n<p>Es importante observar que la situaci\u00f3n ling\u00fc\u00edstica empuja a interpretar la conjunci\u00f3n copulativa de manera diferente en estos enunciados.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">IMPLICATURAS CONVERSACIONALES PARTICULARIZADAS<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El sentido de un enunciado se genera de manera exclusiva debido a las caracter\u00edsticas del contexto.<\/li>\n\n\n\n<li>El sentido del enunciado no se extrae, como en toda la tipolog\u00eda anterior, de lo dicho, sino del contexto.<\/li>\n\n\n\n<li>Por lo tanto, el contexto ling\u00fc\u00edstico, situaciones y sociocultural resulta determinante para la obtenci\u00f3n de la implicatura particularizada.<\/li>\n\n\n\n<li>Resulta indispensable que el emisor y el receptor tengan un conocimiento com\u00fan y compartido.<\/li>\n\n\n\n<li>El receptor infiere la intenci\u00f3n comunicativa del hablante a partir de ese conocimiento compartido.<\/li>\n<\/ul>\n\n\n\n<p><em>(9) El profesor de Pragm\u00e1tica se ha despedido de m\u00ed en un correo con un \u00abatentamente\u00bb<br><\/em>Solamente por el contexto sabemos que un profesor concreto de Pragm\u00e1tica utiliza diferentes f\u00f3rmulas en las despedidas de los correos electr\u00f3nicos y que, cuando lo hace con un \u00abatentamente\u00bb, es una manera de marcar distancias con el receptor.<\/p>\n\n\n\n<p><em>(10) Juan G\u00f3mez Jurado y Arturo P\u00e9rez-Reverte se creen m\u00e1s listos que nadie por poner \u00absolo\u00bb con tilde.<br><\/em>En la pol\u00e9mica sobre el uso de la tilde en <em>solo<\/em> con valor adverbial, zanjada por la <em>Ortograf\u00eda<\/em> de la RAE en su edici\u00f3n de 2010, todav\u00eda hay personajes p\u00fablicos y escritores que se empecinan en utilizar la tilde en estos casos y, con ello, quieren marcar una distancia con la decisi\u00f3n acad\u00e9mica con ciertos tintes de arrogancia. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Para saber m\u00e1s:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Por supuesto, puedes consultar los apartados espec\u00edficos sobre estas cuestiones en la web.<\/strong><\/li>\n\n\n\n<li>Garc\u00eda Muga, F. (2020). Aserci\u00f3n, presuposici\u00f3n e implicatura convencional. En M. V. Escandell Vidal, J. Amen\u00f3s Pons, &amp; A. Ahern (Eds.), <em>Pragm\u00e1tica<\/em> (pp. 79\u2013100). Akal.<\/li>\n\n\n\n<li>Grundy, P. (2020). Doing pragmatics,&nbsp; Routledge, Taylor et Francis Group. <a href=\"https:\/\/doi.org\/10.4324\/9780429300301\">https:\/\/doi.org\/10.4324\/9780429300301<\/a>&nbsp;<\/li>\n\n\n\n<li>Hautli-Janisz, A., Budzynska, K., &amp; Reed, C. (2022). Conventional Implicatures in Argumentation. <em>Languages<\/em>, <em>8<\/em>(1), 14. https:\/\/doi.org\/10.3390\/languages8010014<\/li>\n\n\n\n<li>Korta, K. (2020). La Pragm\u00e1tica. En M. V. Escandell Vidal, J. Amen\u00f3s Pons, &amp; A. Ahern (Eds.), <em>Pragm\u00e1tica<\/em> (pp. 5\u201338). Akal.<\/li>\n\n\n\n<li>Moeschler, J. (2012). Conversational and conventional implicatures. En H. J. Schmid (Ed.), <em>Cognitive Pragmatics<\/em> (pp. 407\u2013434). Mouton De Gruyter. <a href=\"https:\/\/www.researchgate.net\/publication\/260319066_Conversational_and_conventional_implicatures\">https:\/\/www.researchgate.net\/publication\/260319066_Conversational_and_conventional_implicatures<\/a>&nbsp;<\/li>\n\n\n\n<li>Moeschler, J. (2016). Pr\u00e9supposition et implicature: o\u00f9 passe la fronti\u00e8re? In A. Biglari &amp; M. Bonhomme (Eds.), <em>La Pr\u00e9supposition entre th\u00e9orisation et mise en discours<\/em>. Garnier. https:\/\/www.unige.ch\/lettres\/linguistique\/files\/5414\/3135\/1803\/Presupposition_et_implicature.pdf<\/li>\n\n\n\n<li>Vicente Cruz, B. (2020). La implicatura conversacional. In M. V. Escandell Vidal, J. Amen\u00f3s Pons, &amp; A. Ahern (Eds.), <em>Pragm\u00e1tica<\/em> (pp. 101\u2013124). Akal.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Las reflexiones de Grice sobre las presuposiciones los distintos tipos de implicaturas pueden resultar complicados y han dado lugar a detalladas explicaciones por parte de los investigadores en Pragm\u00e1tica. Vamos a intentar dejar aqu\u00ed una breve s\u00edntesis para aclarar conceptos: PRESUPOSICIONES (1) Lorca muri\u00f3 en 1936 en los inicios de la Guerra Civil.(2) Lorca fue &hellip; <a href=\"https:\/\/urbinavolant.com\/pragmaubu\/2024\/03\/28\/compendio-para-explicar-las-presuposiciones-y-las-implicaturas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCompendio para explicar las presuposiciones y las implicaturas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5393","post","type-post","status-publish","format-standard","hentry","category-pragmatica"],"_links":{"self":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/5393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/comments?post=5393"}],"version-history":[{"count":2,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/5393\/revisions"}],"predecessor-version":[{"id":5405,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/5393\/revisions\/5405"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/media?parent=5393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/categories?post=5393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/tags?post=5393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}