{"id":4378,"date":"2019-04-01T09:46:00","date_gmt":"2019-04-01T08:46:00","guid":{"rendered":"http:\/\/urbinavolant.com\/pragmaubu\/?p=4378"},"modified":"2019-04-01T09:46:06","modified_gmt":"2019-04-01T08:46:06","slug":"fragmento-de-el-avaro-de-moliere","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/pragmaubu\/2019\/04\/01\/fragmento-de-el-avaro-de-moliere\/","title":{"rendered":"Fragmento de &#8216;El avaro&#8217; de Moli\u00e8re"},"content":{"rendered":"\n<p>ESCENA XI<\/p>\n\n\n\n<p>HARPAG\u00d3N, MARIANA, CLEANTO, ELISA, VALERIO, FROSINA y MIAJAVENA<\/p>\n\n\n\n<p>HARPAG\u00d3N. Aqu\u00ed est\u00e1 tambi\u00e9n mi hijo, que viene a cumplimentaros.&nbsp;<\/p>\n\n\n\n<p>MARIANA. (<em>Bajo, a&nbsp;<\/em><em>Frosina<\/em>.) \u00a1Ah,&nbsp;Frosina, qu\u00e9 encuentro! Es precisamente el joven de quien te habl\u00e9.&nbsp;<\/p>\n\n\n\n<p>FROSINA. (<em>A Mariana<\/em>.) La aventura es maravillosa.&nbsp;<\/p>\n\n\n\n<p>HARPAG\u00d3N. Veo que os extra\u00f1a ver que tengo unos hijos tan mayores; mas dentro de poco me deshar\u00e9 de ambos.&nbsp;<\/p>\n\n\n\n<p>CLEANTO. (<em>A Mariana<\/em>.)Se\u00f1ora, a deciros verdad, es \u00e9sta una aventura que no me esperaba, sin duda, y mi padre me ha sorprendido bastante al decirme hace un rato el prop\u00f3sito que hab\u00eda forjado.&nbsp;<\/p>\n\n\n\n<p>MARIANA. Yo puedo decir lo mismo. Es un encuentro imprevisto que me asombra tanto como a vos, y no estaba preparada para semejante aventura.<\/p>\n\n\n\n<p>CLEANTO. Cierto es, se\u00f1ora, que mi padre no puede hacer mejor elecci\u00f3n y que representa para m\u00ed una gran alegr\u00eda sensible el veros; mas, con todo, no os aseguro que me regocije el deseo que pod\u00e9is sentir de convertiros en mi madrastra. El parabi\u00e9n, os lo confieso, resulta harto dif\u00edcil para m\u00ed, y es un t\u00edtulo, con vuestra licencia, que no os deseo en modo alguno. Este discurso parecer\u00e1 brutal a los ojos de ciertas personas; mas estoy seguro de que vos lo tomar\u00e9is como es debido; \u00e9ste es un casamiento, se\u00f1ora, que, como os imaginar\u00e9is, me causa aversi\u00f3n; no ignor\u00e1is, sabiendo lo que soy, que ofende mis intereses; y tendr\u00e9, en fin, que deciros, con permiso de mi padre, que, si las cosas dependiesen de m\u00ed, este himeneo no se celebrar\u00eda.&nbsp;<\/p>\n\n\n\n<p>HARPAG\u00d3N. \u00a1Vaya un cumplido impertinente! \u00a1Linda confesi\u00f3n le hac\u00e9is!&nbsp;<\/p>\n\n\n\n<p>MARIANA. Y yo, para contestaros, debo deciros que las cosas son muy semejantes y que, si os causa aversi\u00f3n considerarme como vuestra madrastra, no la sentir\u00e9 yo menor, sin duda, consider\u00e1ndoos como hijastro m\u00edo. No cre\u00e1is, os lo ruego, que soy yo quien intenta produciros esa inquietud. Me disgustar\u00eda grandemente causaros enojo, y, de no yerme obligada a ello por una fuerza irresistible, os doy mi palabra que no acceder\u00e9 en modo alguno al casamiento que os apesadumbra.&nbsp;<\/p>\n\n\n\n<p>HARPAG\u00d3N. Tiene raz\u00f3n. A cumplido necio debe darse una respuesta a tono. Os pido perd\u00f3n, encanto m\u00edo, por la impertinencia de mi hijo; es un joven necio que no conoce todav\u00eda el alcance de las palabras que pronuncia.&nbsp;<\/p>\n\n\n\n<p>MARIANA. Os aseguro que lo que me ha dicho no me ha ofendido en absoluto; al contrario, me complace que me explique as\u00ed sus verdaderos sentimientos. Me agrada en \u00e9l semejante confesi\u00f3n, y si hubiese hablado de otro modo, le estimar\u00eda mucho menos.&nbsp;<\/p>\n\n\n\n<p>HARPAG\u00d3N. Es harta bondad en vos querer disculpar as\u00ed sus faltas. El tiempo le har\u00e1 m\u00e1s cuerdo, y ya ver\u00e9is c\u00f3mo cambia de sentimientos.&nbsp;<\/p>\n\n\n\n<p>CLEANTO. No, padre m\u00edo; no soy capaz de cambiar, y ruego encarecidamente a esta se\u00f1ora que me crea.&nbsp;<\/p>\n\n\n\n<p>HARPAG\u00d3N. \u00bfHasevisto semejante extravagancia? (<em>Eleva a\u00fan m\u00e1s el tono<\/em>.)<\/p>\n\n\n\n<p>CLEANTO. \u00bfQuer\u00e9is que traicione mi coraz\u00f3n?&nbsp;<\/p>\n\n\n\n<p>HARPAG\u00d3N. \u00a1Y dale! \u00bfVais a cambiar de una vez de discurso?&nbsp;<\/p>\n\n\n\n<p>CLEANTO. \u00a1Pues bien! Ya que dese\u00e1is que hable de otra manera, permitid, se\u00f1ora, que me coloque en el lugar de mi padre y que os confiese que no he visto nada en el mundo tan encantador como vos; que no concibo nada igual a la dicha de agradaros, y que el t\u00edtulo de esposo vuestro es una gloria, una felicidad que yo preferir\u00eda al destino de los m\u00e1s grandes pr\u00edncipes de la Tierra&#8230; S\u00ed, se\u00f1ora; la aventura de poseeros es, a mis ojos, la m\u00e1s bella de todas las fortunas; en ella cifro toda mi ambici\u00f3n. Nada hay que no sea capaz de hacer por tan preciada conquista; y los m\u00e1s poderosos obst\u00e1culos&#8230;&nbsp;<\/p>\n\n\n\n<p>HARPAG\u00d3N. Poco a poco, hijo m\u00edo, por favor.&nbsp;<\/p>\n\n\n\n<p>CLEANTO. Es un cumplido que hago a esta se\u00f1ora en nombre vuestro.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESCENA XI HARPAG\u00d3N, MARIANA, CLEANTO, ELISA, VALERIO, FROSINA y MIAJAVENA HARPAG\u00d3N. Aqu\u00ed est\u00e1 tambi\u00e9n mi hijo, que viene a cumplimentaros.&nbsp; MARIANA. (Bajo, a&nbsp;Frosina.) \u00a1Ah,&nbsp;Frosina, qu\u00e9 encuentro! Es precisamente el joven de quien te habl\u00e9.&nbsp; FROSINA. (A Mariana.) La aventura es maravillosa.&nbsp; HARPAG\u00d3N. Veo que os extra\u00f1a ver que tengo unos hijos tan mayores; mas dentro &hellip; <a href=\"https:\/\/urbinavolant.com\/pragmaubu\/2019\/04\/01\/fragmento-de-el-avaro-de-moliere\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFragmento de &#8216;El avaro&#8217; de Moli\u00e8re\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4378","post","type-post","status-publish","format-standard","hentry","category-pragmatica"],"_links":{"self":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/4378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/comments?post=4378"}],"version-history":[{"count":1,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/4378\/revisions"}],"predecessor-version":[{"id":4379,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/4378\/revisions\/4379"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/media?parent=4378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/categories?post=4378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/tags?post=4378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}