{"id":3957,"date":"2016-05-13T07:25:50","date_gmt":"2016-05-13T06:25:50","guid":{"rendered":"http:\/\/urbinavolant.com\/pragmaubu\/?p=3957"},"modified":"2016-05-13T07:29:57","modified_gmt":"2016-05-13T06:29:57","slug":"los-actos-comunicativos-corteses-y-descorteses","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/pragmaubu\/2016\/05\/13\/los-actos-comunicativos-corteses-y-descorteses\/","title":{"rendered":"Los actos comunicativos corteses y descorteses"},"content":{"rendered":"<h3>\u00bfC\u00f3mo se reacciona ante la (des)cortes\u00eda del emisor?<\/h3>\n<ul>\n<li>Con otro acto cort\u00e9s. Mantenemos el intercambio.<\/li>\n<li>Con descortes\u00eda. Se rompe la interacci\u00f3n o se la lleva al enfrentamiento.<\/li>\n<\/ul>\n<h3>Cortes\u00eda en los actos rituales<\/h3>\n<p style=\"text-align: justify;\">Incluso en actos rituales como el saludo, la bienvenida, la despedida, la presentaci\u00f3n, etc. es importante la cortes\u00eda.\u00a0Gracias a la cortes\u00eda, damos a nuestro interlocutor una imagen de educaci\u00f3n.<\/p>\n<h3 style=\"text-align: justify;\">Elementos del acto comunicativo (des)cort\u00e9s<\/h3>\n<ul>\n<li style=\"text-align: justify;\">El emisor. Intentar salvaguardar la imagen propia.<\/li>\n<li style=\"text-align: justify;\">El receptor. Se utilizan estrategias argumentativas para preservar (o no) su imagen.<\/li>\n<li style=\"text-align: justify;\">El contexto.<\/li>\n<\/ul>\n<h3>La importancia del contexto<\/h3>\n<p style=\"text-align: justify;\">El <strong>contexto sociocultural<\/strong> determina lo adecuado para cada caso y si una manifestaci\u00f3n discursiva es cort\u00e9s o descort\u00e9s. Var\u00eda mucho de unas culturas a otras.<\/p>\n<p style=\"text-align: justify;\">El <strong>contexto ling\u00fc\u00edstico<\/strong>. Los elementos que aparecen en el discurso pueden atenuar o enfatizar un acto cort\u00e9s o descort\u00e9s.<\/p>\n<p style=\"text-align: justify;\">El<strong> tipo de modalidad textual<\/strong>. No es lo mismo una conversaci\u00f3n informal, una intervenci\u00f3n pol\u00edtica, un acto acad\u00e9mico\u2026<\/p>\n<h3 style=\"text-align: justify;\">\u00bfC\u00f3mo se provoca la descortes\u00eda?<\/h3>\n<p style=\"text-align: justify;\">En la descortes\u00eda se produce un ataque a la imagen del receptor.<\/p>\n<p style=\"text-align: justify;\">El receptor puede reaccionar de varias maneras:<\/p>\n<ul>\n<li>Contrariar:\n<ul>\n<li>Ofensivamente (atacar la imagen ajena).<\/li>\n<li>Defensivamente (defender la imagen propia).<\/li>\n<\/ul>\n<\/li>\n<li>Aceptar: asumir su responsabilidad, pedir disculpas (se da\u00f1a la propia imagen).<\/li>\n<li>Ausencia de respuesta (silencio).<\/li>\n<\/ul>\n<h3>Factores para determinar la (des)cortes\u00eda<\/h3>\n<p><a href=\"http:\/\/urbinavolant.com\/pragmaubu\/2016\/05\/13\/los-actos-comunicativos-corteses-y-descorteses\/captura-de-pantalla-2016-05-13-a-las-8-29-07\/\" rel=\"attachment wp-att-3960\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3960\" src=\"http:\/\/urbinavolant.com\/pragmaubu\/wp-content\/uploads\/2016\/05\/Captura-de-pantalla-2016-05-13-a-las-8.29.07-1024x149.png\" alt=\"FactoresCortes\u00eda\" width=\"840\" height=\"122\" srcset=\"https:\/\/urbinavolant.com\/pragmaubu\/wp-content\/uploads\/2016\/05\/Captura-de-pantalla-2016-05-13-a-las-8.29.07-1024x149.png 1024w, https:\/\/urbinavolant.com\/pragmaubu\/wp-content\/uploads\/2016\/05\/Captura-de-pantalla-2016-05-13-a-las-8.29.07-300x44.png 300w, https:\/\/urbinavolant.com\/pragmaubu\/wp-content\/uploads\/2016\/05\/Captura-de-pantalla-2016-05-13-a-las-8.29.07-768x112.png 768w, https:\/\/urbinavolant.com\/pragmaubu\/wp-content\/uploads\/2016\/05\/Captura-de-pantalla-2016-05-13-a-las-8.29.07-1200x175.png 1200w, https:\/\/urbinavolant.com\/pragmaubu\/wp-content\/uploads\/2016\/05\/Captura-de-pantalla-2016-05-13-a-las-8.29.07.png 1791w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo se reacciona ante la (des)cortes\u00eda del emisor? Con otro acto cort\u00e9s. Mantenemos el intercambio. Con descortes\u00eda. Se rompe la interacci\u00f3n o se la lleva al enfrentamiento. Cortes\u00eda en los actos rituales Incluso en actos rituales como el saludo, la bienvenida, la despedida, la presentaci\u00f3n, etc. es importante la cortes\u00eda.\u00a0Gracias a la cortes\u00eda, damos a &hellip; <a href=\"https:\/\/urbinavolant.com\/pragmaubu\/2016\/05\/13\/los-actos-comunicativos-corteses-y-descorteses\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLos actos comunicativos corteses y descorteses\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3957","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/comments?post=3957"}],"version-history":[{"count":3,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3957\/revisions"}],"predecessor-version":[{"id":3961,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3957\/revisions\/3961"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/media?parent=3957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/categories?post=3957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/tags?post=3957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}