{"id":3821,"date":"2016-04-06T10:41:39","date_gmt":"2016-04-06T09:41:39","guid":{"rendered":"http:\/\/urbinavolant.com\/pragmaubu\/?p=3821"},"modified":"2016-04-12T08:18:57","modified_gmt":"2016-04-12T07:18:57","slug":"el-principio-de-cooperacion","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/pragmaubu\/2016\/04\/06\/el-principio-de-cooperacion\/","title":{"rendered":"El principio de cooperaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">Nuestros intercambios comunicativos corrientes no consisten en una sucesi\u00f3n de observaciones desconectadas.\u00a0La conversaci\u00f3n comporta, normalmente, un esfuerzo por colaborar con nuestro interlocutor: los hablantes tienen por lo general alg\u00fan prop\u00f3sito com\u00fan, m\u00e1s o menos definido, y tratan de alcanzarlo.<\/p>\n<p style=\"text-align: justify;\">El principio de cooperaci\u00f3n es el principio general que gu\u00eda a los interlocutores en la conversaci\u00f3n, y que vale tambi\u00e9n para otros comportamientos.\u00a0Grice lo formula as\u00ed:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u00abSu aporte a la conversaci\u00f3n debe ser, en cada etapa de esta, tal como lo exija la finalidad o la direcci\u00f3n del intercambio verbal aceptada por ambas partes\u201d.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">\u00abDebemos\u00bb comportarnos as\u00ed porque es lo que los dem\u00e1s esperan de nosotros, y nosotros de los dem\u00e1s.\u00a0La expectativa es tan fuerte que, si el hablante parece no cumplir con el principio de cooperaci\u00f3n, el oyente, en lugar de pensar que efectivamente el hablante no cumple, va a pensar que el hablante quiere decir otra cosa.\u00a0Esa otra cosa ser\u00e1 una implicatura, es decir, un significado adicional comunicado por el hablante e inferido por el oyente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros intercambios comunicativos corrientes no consisten en una sucesi\u00f3n de observaciones desconectadas.\u00a0La conversaci\u00f3n comporta, normalmente, un esfuerzo por colaborar con nuestro interlocutor: los hablantes tienen por lo general alg\u00fan prop\u00f3sito com\u00fan, m\u00e1s o menos definido, y tratan de alcanzarlo. El principio de cooperaci\u00f3n es el principio general que gu\u00eda a los interlocutores en la conversaci\u00f3n, &hellip; <a href=\"https:\/\/urbinavolant.com\/pragmaubu\/2016\/04\/06\/el-principio-de-cooperacion\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl principio de cooperaci\u00f3n\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3821","post","type-post","status-publish","format-standard","hentry","category-pragmatica"],"_links":{"self":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/comments?post=3821"}],"version-history":[{"count":3,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3821\/revisions"}],"predecessor-version":[{"id":3825,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3821\/revisions\/3825"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/media?parent=3821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/categories?post=3821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/tags?post=3821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}