{"id":3694,"date":"2016-02-12T19:43:05","date_gmt":"2016-02-12T18:43:05","guid":{"rendered":"http:\/\/urbinavolant.com\/pragmaubu\/?p=3694"},"modified":"2024-02-15T17:44:15","modified_gmt":"2024-02-15T16:44:15","slug":"evolucion-de-la-pragmatica","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/pragmaubu\/2016\/02\/12\/evolucion-de-la-pragmatica\/","title":{"rendered":"Evoluci\u00f3n de la Pragm\u00e1tica"},"content":{"rendered":"<p style=\"text-align: justify;\">Adem\u00e1s de los precedentes m\u00e1s o menos remotos que se han mencionado, podemos dividir la evoluci\u00f3n de la Pragm\u00e1tica en tres grandes etapas.<\/p>\n<p style=\"text-align: justify;\">En el fondo, subyace el debate en torno a si podemos (o no) considerar a la Pragm\u00e1tica como\u00a0una disciplina \u00a0ling\u00fc\u00edstica.<\/p>\n<h3 style=\"text-align: justify;\">Pragm\u00e1tica formalista (a\u00f1os 30 y 40 del siglo XX)<\/h3>\n<p style=\"text-align: justify;\">En esta \u00e9poca (Peirce, Morris), se concibe a la Pragm\u00e1tica como parte integrante de un sistema semi\u00f3tico.<\/p>\n<p style=\"text-align: justify;\">En esta primera etapa, se tiene una concepci\u00f3n bastante limitada, por la cual la Pragm\u00e1tica se ocupa de una peque\u00f1a parte de elementos que se escapan a otros niveles de estudio ling\u00fc\u00edstico como, por ejemplo, los de\u00edcticos.<\/p>\n<h3 style=\"text-align: justify;\">Los fil\u00f3sofos del lenguaje (entre los a\u00f1os 50 y 70 del siglo XX)<\/h3>\n<p style=\"text-align: justify;\">Es una \u00e9poca en la que se empiezan a cuestionar los presupuestos de la filosof\u00eda anal\u00edtica y el modelo l\u00f3gico-matem\u00e1tico que la sustentaba.<\/p>\n<p style=\"text-align: justify;\">Con el precedente del \u00absegundo Wittgenstein\u00bb de las <em>Investigaciones filos\u00f3ficas<\/em>, todo un conjunto de fil\u00f3sofos del lenguaje, inicialmente anglosajones (Strawson, Austin, Grice) y luego norteamericanos (Searle) se vuelcan en el estudio del lenguaje ordinario, convencidos, adem\u00e1s, de que el lenguaje no es solo descriptivo, sino que sirve para realizar acciones.<\/p>\n<p style=\"text-align: justify;\">En esta etapa el campo de la Pragm\u00e1tica es bastante m\u00e1s extenso. Aunque es una disciplina en pleno proceso de consolidaci\u00f3n, todav\u00eda contaba, sin embargo, con ciertas reticencias, dado que su campo de acci\u00f3n era \u00abnegativo\u00bb (la Pragm\u00e1tica estudiaba lo que <em>no<\/em> estudiaban las dem\u00e1s disciplinas) y precisaba del uso cruzado de muchas disciplinas. Estos inconvenientes hac\u00edan que no fuera a\u00fan una ciencia totalmente reconocida.<\/p>\n<h3 style=\"text-align: justify;\">Pragm\u00e1tica cognitiva y Pragm\u00e1tica integrada (a\u00f1os 80 y 90 del siglo XX)<\/h3>\n<p style=\"text-align: justify;\">En estos a\u00f1os, la Pragm\u00e1tica evolucionar\u00e1 en dos sentidos diferentes. En el \u00e1mbito anglosaj\u00f3n, triunfa la Pragm\u00e1tica cognitiva, mientras que en el \u00e1mbito franc\u00e9s predomina la Pragm\u00e1tica integrada a la ling\u00fc\u00edstica.<\/p>\n<h6 style=\"text-align: justify;\">Pragm\u00e1tica cognitiva<\/h6>\n<p style=\"text-align: justify;\">La Ling\u00fc\u00edstica y la Pragm\u00e1tica se conciben como ciencias vecinas \u00a0y complementarias, susceptibles de tener puntos en com\u00fan.<\/p>\n<ul>\n<li style=\"text-align: justify;\">La Pragm\u00e1tica se orienta hacia la <strong>socioling\u00fc\u00edstica<\/strong> cuando hace hincapi\u00e9 en las funciones del lenguaje (Labov, Goffman).<\/li>\n<li style=\"text-align: justify;\">Se orienta hacia la <strong>psicoling\u00fc\u00edstica<\/strong> cuando hace hincapi\u00e9 en los procesos de adquisici\u00f3n y tratamiento de la informaci\u00f3n (Milner, Charoles).<\/li>\n<li style=\"text-align: justify;\">Se orienta hacia las <strong>ciencias cognitivas<\/strong>, que consideran que el tratamiento pragm\u00e1tico de la informaci\u00f3n revela un sistema central de pensamiento y definen una Pragm\u00e1tica deductiva encargada de analizar los procesos inferenciales generales, universales y no espec\u00edficos ni exclusivos del lenguaje. Esta Pragm\u00e1tica cognitiva intenta estudiar las relaciones entre el lenguaje y sus usuarios en relaci\u00f3n al tratamiento que hacen estos de la informaci\u00f3n de acuerdo con un sistema de adecuaci\u00f3n lo m\u00e1s \u00f3ptimo posible (Dan Sperber y Deirdre Wilson).<\/li>\n<\/ul>\n<h6>Pragm\u00e1tica integrada<\/h6>\n<p style=\"text-align: justify;\">Algunos investigadores franceses (Anscombre, Ducrot, R\u00e9canati, Kerbrat-Orecchioni) realizan un estudio complementario entre la Pragm\u00e1tica y la Sem\u00e1ntica. En este sentido, la Pragm\u00e1tica se encarga esencialmente de describir la situaci\u00f3n de comunicaci\u00f3n, las condiciones para que una comunicaci\u00f3n tenga \u00e9xito y el estudio de palabras situaciones, como los de\u00edcticos. Acoge, pues, los aspectos del c\u00f3digo ligados a la enunciaci\u00f3n. Derivar\u00e1 tambi\u00e9n en las teor\u00edas pragm\u00e1ticas argumentativas.<\/p>\n<h3>En la actualidad<\/h3>\n<p style=\"text-align: justify;\">La pragm\u00e1tica se ha convertido en un campo de estudio esencial para la ciencia cognitiva, la inteligencia artificial, la traducci\u00f3n autom\u00e1tica, la inform\u00e1tica, la neurociencia o las patolog\u00edas del lenguaje, por poner solo algunos ejemplos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de los precedentes m\u00e1s o menos remotos que se han mencionado, podemos dividir la evoluci\u00f3n de la Pragm\u00e1tica en tres grandes etapas. En el fondo, subyace el debate en torno a si podemos (o no) considerar a la Pragm\u00e1tica como\u00a0una disciplina \u00a0ling\u00fc\u00edstica. Pragm\u00e1tica formalista (a\u00f1os 30 y 40 del siglo XX) En esta \u00e9poca &hellip; <a href=\"https:\/\/urbinavolant.com\/pragmaubu\/2016\/02\/12\/evolucion-de-la-pragmatica\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEvoluci\u00f3n de la Pragm\u00e1tica\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3694","post","type-post","status-publish","format-standard","hentry","category-pragmatica"],"_links":{"self":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/comments?post=3694"}],"version-history":[{"count":4,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3694\/revisions"}],"predecessor-version":[{"id":5373,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/posts\/3694\/revisions\/5373"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/media?parent=3694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/categories?post=3694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/pragmaubu\/wp-json\/wp\/v2\/tags?post=3694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}