{"id":4298,"date":"2018-03-03T13:28:34","date_gmt":"2018-03-03T12:28:34","guid":{"rendered":"http:\/\/urbinavolant.com\/argumentos\/?p=4298"},"modified":"2018-03-14T13:13:08","modified_gmt":"2018-03-14T12:13:08","slug":"estructuras-argumentativas","status":"publish","type":"post","link":"https:\/\/urbinavolant.com\/argumentos\/2018\/03\/03\/estructuras-argumentativas\/","title":{"rendered":"Estructuras argumentativas"},"content":{"rendered":"<p>Estructuras argumentativas (Fuentes Rodr\u00edguez &amp; Alcaide Lara, 2007, pp. 43\u201353).<\/p>\n<h3 style=\"text-align: justify;\">Estructuras argumentativas simples<\/h3>\n<p style=\"text-align: justify;\">El esquema es argumento\u00a0\u2192 conclusi\u00f3n<\/p>\n<p style=\"text-align: justify;\">Este esquema puede ser ampliado, si es necesario, haciendo expl\u00edcita la base argumentativa.<\/p>\n<p style=\"text-align: justify;\">La estructura funcional de cada argumento puede contener varios argumentos a favor o en contra de una conclusi\u00f3n (que haya varios argumentos no es sin\u00f3nimo de una estructura m\u00faltiple).<\/p>\n<p style=\"text-align: justify;\">Las estructuras argumentativas simples pueden ser:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Conclusi\u00f3n-argumento. Se parte de lo general a lo particular.<\/li>\n<li style=\"text-align: justify;\">Argumento-conclusi\u00f3n. Se sigue un proceso deductivo de lo particular a lo general.<\/li>\n<li style=\"text-align: justify;\">Contraposici\u00f3n. Se rechaza lo que no es. Se parte de la postura contraria para rechazar, de este modo, posibles objeciones.<\/li>\n<li style=\"text-align: justify;\">Componentes b\u00e1sicos acompa\u00f1ados de alg\u00fan elemento que aporte fuerza argumentativa en el argumento o en la conclusi\u00f3n. Este elemento subraya la fuerza argumentativa de la argumentaci\u00f3n.<\/li>\n<li>Encadenamiento argumentativo acompa\u00f1ado de la base argumentativa.<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">Estructuras argumentativas complejas<\/h3>\n<p style=\"text-align: justify;\">El esquema es tambi\u00e9n argumento\u00a0\u2192 conclusi\u00f3n, pero el argumento puede estar formado por otro encadenamiento argumentativo del mismo tipo. Se hace manifiesta la ley de recursividad: unidades mayores pueden desempe\u00f1ar la funci\u00f3n de unidades menores.<\/p>\n<p style=\"text-align: justify;\">Las estructuras argumentativas complejas pueden ser:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Movimiento argumentativo complejo como argumento de una conclusi\u00f3n: recursividad argumentativa o construcci\u00f3n arracimada.<\/li>\n<li style=\"text-align: justify;\">Coorientaci\u00f3n + antiorientaci\u00f3n. El hablante expone argumentos para demostrar su opini\u00f3n y rebate, al mismo tiempo, otras posibles opiniones.<\/li>\n<li style=\"text-align: justify;\">Reserva. Establece unas circunstancias en las que hay que reintepretar y relativizar todo lo dicho con anterioridad, de modo que se puede llegar a conclusiones contrarias a la expuesta.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"margin-left: 24pt; text-indent: -24.0pt;\">Fuentes Rodr\u00edguez, C., &amp; Alcaide Lara, E. R. (2007). <i>La argumentaci\u00f3n ling\u00fc\u00edstica y sus medios de expresi\u00f3n<\/i>. Madrid: Arco Libros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estructuras argumentativas (Fuentes Rodr\u00edguez &amp; Alcaide Lara, 2007, pp. 43\u201353). Estructuras argumentativas simples El esquema es argumento\u00a0\u2192 conclusi\u00f3n Este esquema puede ser ampliado, si es necesario, haciendo expl\u00edcita la base argumentativa. La estructura funcional de cada argumento puede contener varios argumentos a favor o en contra de una conclusi\u00f3n (que haya varios argumentos no es &hellip; <a href=\"https:\/\/urbinavolant.com\/argumentos\/2018\/03\/03\/estructuras-argumentativas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstructuras argumentativas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/posts\/4298"}],"collection":[{"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/comments?post=4298"}],"version-history":[{"count":3,"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/posts\/4298\/revisions"}],"predecessor-version":[{"id":4377,"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/posts\/4298\/revisions\/4377"}],"wp:attachment":[{"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/media?parent=4298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/categories?post=4298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbinavolant.com\/argumentos\/wp-json\/wp\/v2\/tags?post=4298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}